{"id":5071,"date":"2024-12-04T08:15:58","date_gmt":"2024-12-04T08:15:58","guid":{"rendered":"https:\/\/rc-hall.com\/listing\/helion\/"},"modified":"2024-12-04T08:15:58","modified_gmt":"2024-12-04T08:15:58","slug":"helion","status":"publish","type":"listing","link":"https:\/\/rc-hall.com\/es\/listing\/helion\/","title":{"rendered":"Helion"},"content":{"rendered":"<p>Helion ist ein international bekannter Hersteller von hochwertigen RC-Car-Fahrzeugen, insbesondere im Bereich von Einsteiger- und Hobby-Modellen. Das Unternehmen hat eine breite Produktpalette, die sich an Anf\u00e4nger und Freizeitfahrer richtet. Helion-RC-Fahrzeuge sind f\u00fcr ihre Benutzerfreundlichkeit und Haltbarkeit bekannt und bieten eine ideale Einstiegsoption f\u00fcr Neueinsteiger in das RC-Hobby. Mit einer vielf\u00e4ltigen Modellauswahl hat sich Helion als vertrauensw\u00fcrdige Marke f\u00fcr RC-Enthusiasten weltweit etabliert.<\/p>","protected":false},"author":1,"featured_media":5072,"comment_status":"open","ping_status":"closed","template":"","format":"standard","meta":[],"listing-category":[4243],"listing-tag":[4248],"listing-locations":[],"class_list":["post-5071","listing","type-listing","status-publish","format-standard","has-post-thumbnail","hentry","listing-category-hersteller","listing-tag-rc-cars"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.3 (Yoast SEO v25.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Helion - RC Hall<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rc-hall.com\/es\/listing\/helion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Helion\" \/>\n<meta property=\"og:description\" content=\"Helion ist ein international bekannter Hersteller von hochwertigen RC-Car-Fahrzeugen, insbesondere im Bereich von Einsteiger- und Hobby-Modellen. Das Unternehmen hat eine breite Produktpalette, die sich an Anf\u00e4nger und Freizeitfahrer richtet. Helion-RC-Fahrzeuge sind f\u00fcr ihre Benutzerfreundlichkeit und Haltbarkeit bekannt und bieten eine ideale Einstiegsoption f\u00fcr Neueinsteiger in das RC-Hobby. Mit einer vielf\u00e4ltigen Modellauswahl hat sich Helion als [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rc-hall.com\/es\/listing\/helion\/\" \/>\n<meta property=\"og:site_name\" content=\"RC Hall\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/rc-hall.com\/listing\/helion\/\",\"url\":\"https:\/\/rc-hall.com\/listing\/helion\/\",\"name\":\"Helion - RC Hall\",\"isPartOf\":{\"@id\":\"https:\/\/rc-hall.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/rc-hall.com\/listing\/helion\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/rc-hall.com\/listing\/helion\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/rc-hall.com\/wp-content\/uploads\/2024\/12\/HLN_logo.gif\",\"datePublished\":\"2024-12-04T08:15:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/rc-hall.com\/listing\/helion\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/rc-hall.com\/listing\/helion\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/rc-hall.com\/listing\/helion\/#primaryimage\",\"url\":\"https:\/\/rc-hall.com\/wp-content\/uploads\/2024\/12\/HLN_logo.gif\",\"contentUrl\":\"https:\/\/rc-hall.com\/wp-content\/uploads\/2024\/12\/HLN_logo.gif\",\"width\":75,\"height\":17},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/rc-hall.com\/listing\/helion\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/rc-hall.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Listing\",\"item\":\"https:\/\/rc-hall.com\/listing\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Helion\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/rc-hall.com\/#website\",\"url\":\"https:\/\/rc-hall.com\/\",\"name\":\"RC Hall\",\"description\":\"Der Begleiter f\u00fcr das schnelle Hobby auf vier R\u00e4dern!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/rc-hall.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Helion - RC Hall","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rc-hall.com\/es\/listing\/helion\/","og_locale":"es_ES","og_type":"article","og_title":"Helion","og_description":"Helion ist ein international bekannter Hersteller von hochwertigen RC-Car-Fahrzeugen, insbesondere im Bereich von Einsteiger- und Hobby-Modellen. Das Unternehmen hat eine breite Produktpalette, die sich an Anf\u00e4nger und Freizeitfahrer richtet. Helion-RC-Fahrzeuge sind f\u00fcr ihre Benutzerfreundlichkeit und Haltbarkeit bekannt und bieten eine ideale Einstiegsoption f\u00fcr Neueinsteiger in das RC-Hobby. Mit einer vielf\u00e4ltigen Modellauswahl hat sich Helion als [&hellip;]","og_url":"https:\/\/rc-hall.com\/es\/listing\/helion\/","og_site_name":"RC Hall","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rc-hall.com\/listing\/helion\/","url":"https:\/\/rc-hall.com\/listing\/helion\/","name":"Helion - RC Hall","isPartOf":{"@id":"https:\/\/rc-hall.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rc-hall.com\/listing\/helion\/#primaryimage"},"image":{"@id":"https:\/\/rc-hall.com\/listing\/helion\/#primaryimage"},"thumbnailUrl":"https:\/\/rc-hall.com\/wp-content\/uploads\/2024\/12\/HLN_logo.gif","datePublished":"2024-12-04T08:15:58+00:00","breadcrumb":{"@id":"https:\/\/rc-hall.com\/listing\/helion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rc-hall.com\/listing\/helion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rc-hall.com\/listing\/helion\/#primaryimage","url":"https:\/\/rc-hall.com\/wp-content\/uploads\/2024\/12\/HLN_logo.gif","contentUrl":"https:\/\/rc-hall.com\/wp-content\/uploads\/2024\/12\/HLN_logo.gif","width":75,"height":17},{"@type":"BreadcrumbList","@id":"https:\/\/rc-hall.com\/listing\/helion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/rc-hall.com\/"},{"@type":"ListItem","position":2,"name":"Listing","item":"https:\/\/rc-hall.com\/listing\/"},{"@type":"ListItem","position":3,"name":"Helion"}]},{"@type":"WebSite","@id":"https:\/\/rc-hall.com\/#website","url":"https:\/\/rc-hall.com\/","name":"RC Hall","description":"Der Begleiter f\u00fcr das schnelle Hobby auf vier R\u00e4dern!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rc-hall.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/rc-hall.com\/es\/wp-json\/wp\/v2\/listing\/5071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rc-hall.com\/es\/wp-json\/wp\/v2\/listing"}],"about":[{"href":"https:\/\/rc-hall.com\/es\/wp-json\/wp\/v2\/types\/listing"}],"author":[{"embeddable":true,"href":"https:\/\/rc-hall.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rc-hall.com\/es\/wp-json\/wp\/v2\/comments?post=5071"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rc-hall.com\/es\/wp-json\/wp\/v2\/media\/5072"}],"wp:attachment":[{"href":"https:\/\/rc-hall.com\/es\/wp-json\/wp\/v2\/media?parent=5071"}],"wp:term":[{"taxonomy":"listing-category","embeddable":true,"href":"https:\/\/rc-hall.com\/es\/wp-json\/wp\/v2\/listing-category?post=5071"},{"taxonomy":"listing-tag","embeddable":true,"href":"https:\/\/rc-hall.com\/es\/wp-json\/wp\/v2\/listing-tag?post=5071"},{"taxonomy":"listing-locations","embeddable":true,"href":"https:\/\/rc-hall.com\/es\/wp-json\/wp\/v2\/listing-locations?post=5071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}